{"id":1660,"date":"2020-01-31T09:56:07","date_gmt":"2020-01-31T09:56:07","guid":{"rendered":"https:\/\/seafishingslovenia.com\/?p=1660"},"modified":"2020-01-31T09:56:08","modified_gmt":"2020-01-31T09:56:08","slug":"slovenske-lampugedelfinke-poznane-tudi-v-rusiji","status":"publish","type":"post","link":"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/","title":{"rendered":"Slovenske lampuge(delfinke) poznane tudi v Rusiji"},"content":{"rendered":"\n<p> &#8221;Lampugarska&#8221; sezona 2018 je bila res uspe\u0161na. Za\u010delo se je sredi avgusta, s \u0161tevilnimi jatami manj\u0161ih lampug. Konec avgusta sem vzel na ribolov Iliyo Fisher, novinarja, ki dela za rusko revijo Avtomir. Po uspe\u0161nem ribolovu s sinom je bil tako navdu\u0161en nad tem, da je napisal \u010dlanek o ribolovnem potovanju. <\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/47681471_381973725881452_2882643678113824768_n-1-768x1024-1.jpg\" alt=\"\" data-id=\"1661\" data-full-url=\"https:\/\/seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/47681471_381973725881452_2882643678113824768_n-1-768x1024-1.jpg\" data-link=\"https:\/\/seafishingslovenia.com\/?attachment_id=1661\" class=\"wp-image-1661\" srcset=\"http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/47681471_381973725881452_2882643678113824768_n-1-768x1024-1.jpg 768w, http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/47681471_381973725881452_2882643678113824768_n-1-768x1024-1-225x300.jpg 225w, http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/47681471_381973725881452_2882643678113824768_n-1-768x1024-1-370x493.jpg 370w, http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/47681471_381973725881452_2882643678113824768_n-1-768x1024-1-740x986.jpg 740w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48187916_289814245001622_5520253355957420032_n-1-768x1024-1.jpg\" alt=\"\" data-id=\"1662\" data-full-url=\"https:\/\/seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48187916_289814245001622_5520253355957420032_n-1-768x1024-1.jpg\" data-link=\"https:\/\/seafishingslovenia.com\/?attachment_id=1662\" class=\"wp-image-1662\" srcset=\"http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48187916_289814245001622_5520253355957420032_n-1-768x1024-1.jpg 768w, http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48187916_289814245001622_5520253355957420032_n-1-768x1024-1-225x300.jpg 225w, http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48187916_289814245001622_5520253355957420032_n-1-768x1024-1-370x493.jpg 370w, http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48187916_289814245001622_5520253355957420032_n-1-768x1024-1-740x986.jpg 740w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48361047_1997076737042660_2784852890601127936_n-1-768x1024-1.jpg\" alt=\"\" data-id=\"1663\" data-full-url=\"https:\/\/seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48361047_1997076737042660_2784852890601127936_n-1-768x1024-1.jpg\" data-link=\"https:\/\/seafishingslovenia.com\/?attachment_id=1663\" class=\"wp-image-1663\" srcset=\"http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48361047_1997076737042660_2784852890601127936_n-1-768x1024-1.jpg 768w, http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48361047_1997076737042660_2784852890601127936_n-1-768x1024-1-225x300.jpg 225w, http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48361047_1997076737042660_2784852890601127936_n-1-768x1024-1-370x493.jpg 370w, http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48361047_1997076737042660_2784852890601127936_n-1-768x1024-1-740x986.jpg 740w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1.jpg\" alt=\"\" data-id=\"1664\" data-full-url=\"https:\/\/seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1.jpg\" data-link=\"https:\/\/seafishingslovenia.com\/?attachment_id=1664\" class=\"wp-image-1664\" srcset=\"http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1.jpg 768w, http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1-225x300.jpg 225w, http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1-370x493.jpg 370w, http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1-740x986.jpg 740w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>&#8221;Lampugarska&#8221; sezona 2018 je bila res uspe\u0161na. Za\u010delo se je sredi avgusta, s \u0161tevilnimi jatami manj\u0161ih lampug. Konec avgusta sem vzel na ribolov Iliyo Fisher, novinarja, ki dela za rusko revijo Avtomir. Po uspe\u0161nem ribolovu s sinom je bil tako navdu\u0161en nad tem, da je napisal \u010dlanek o ribolovnem potovanju.<\/p>\n","protected":false},"author":990004,"featured_media":1664,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[91],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Slovenske lampuge(delfinke) poznane tudi v Rusiji - Vodeni ribolov v slovenskem morju<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/\" \/>\n<meta property=\"og:locale\" content=\"sl_SI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slovenske lampuge(delfinke) poznane tudi v Rusiji - Vodeni ribolov v slovenskem morju\" \/>\n<meta property=\"og:description\" content=\"&#8221;Lampugarska&#8221; sezona 2018 je bila res uspe\u0161na. Za\u010delo se je sredi avgusta, s \u0161tevilnimi jatami manj\u0161ih lampug. Konec avgusta sem vzel na ribolov Iliyo Fisher, novinarja, ki dela za rusko revijo Avtomir. Po uspe\u0161nem ribolovu s sinom je bil tako navdu\u0161en nad tem, da je napisal \u010dlanek o ribolovnem potovanju.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/\" \/>\n<meta property=\"og:site_name\" content=\"Vodeni ribolov v slovenskem morju\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/seafishingslovenia\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-31T09:56:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-31T09:56:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Peter Kodre\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/en.seafishingslovenia.com\/#organization\",\"name\":\"Ribolov v slovenskem morju\",\"url\":\"https:\/\/en.seafishingslovenia.com\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/seafishingslovenia\/\",\"https:\/\/www.instagram.com\/seafishingslovenia\/\",\"https:\/\/www.youtube.com\/channel\/UCX9hrnSWUMivTMsSQa_gQPw\/videos\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/en.seafishingslovenia.com\/#logo\",\"inLanguage\":\"sl-SI\",\"url\":\"http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/2-layers.png\",\"contentUrl\":\"http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/2-layers.png\",\"width\":91,\"height\":44,\"caption\":\"Ribolov v slovenskem morju\"},\"image\":{\"@id\":\"https:\/\/en.seafishingslovenia.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/en.seafishingslovenia.com\/#website\",\"url\":\"https:\/\/en.seafishingslovenia.com\/\",\"name\":\"Ribolov v slovenskem morju vodeni morski ribolov\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/en.seafishingslovenia.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/en.seafishingslovenia.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sl-SI\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#primaryimage\",\"inLanguage\":\"sl-SI\",\"url\":\"http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1.jpg\",\"contentUrl\":\"http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1.jpg\",\"width\":768,\"height\":1024,\"caption\":\"avtomir-ravija\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#webpage\",\"url\":\"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/\",\"name\":\"Slovenske lampuge(delfinke) poznane tudi v Rusiji - Vodeni ribolov v slovenskem morju\",\"isPartOf\":{\"@id\":\"https:\/\/en.seafishingslovenia.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#primaryimage\"},\"datePublished\":\"2020-01-31T09:56:07+00:00\",\"dateModified\":\"2020-01-31T09:56:08+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#breadcrumb\"},\"inLanguage\":\"sl-SI\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/en.seafishingslovenia.com\/sl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slovenske lampuge(delfinke) poznane tudi v Rusiji\"}]},{\"@type\":\"Article\",\"@id\":\"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#webpage\"},\"author\":{\"@id\":\"https:\/\/en.seafishingslovenia.com\/#\/schema\/person\/25a30ee74697b01e244b0ffebbda054b\"},\"headline\":\"Slovenske lampuge(delfinke) poznane tudi v Rusiji\",\"datePublished\":\"2020-01-31T09:56:07+00:00\",\"dateModified\":\"2020-01-31T09:56:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#webpage\"},\"wordCount\":61,\"publisher\":{\"@id\":\"https:\/\/en.seafishingslovenia.com\/#organization\"},\"image\":{\"@id\":\"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1.jpg\",\"articleSection\":[\"Uncategorized @sl\"],\"inLanguage\":\"sl-SI\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/en.seafishingslovenia.com\/#\/schema\/person\/25a30ee74697b01e244b0ffebbda054b\",\"name\":\"Peter Kodre\",\"url\":\"http:\/\/en.seafishingslovenia.com\/sl\/author\/peterkodresampei\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Slovenske lampuge(delfinke) poznane tudi v Rusiji - Vodeni ribolov v slovenskem morju","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/","og_locale":"sl_SI","og_type":"article","og_title":"Slovenske lampuge(delfinke) poznane tudi v Rusiji - Vodeni ribolov v slovenskem morju","og_description":"&#8221;Lampugarska&#8221; sezona 2018 je bila res uspe\u0161na. Za\u010delo se je sredi avgusta, s \u0161tevilnimi jatami manj\u0161ih lampug. Konec avgusta sem vzel na ribolov Iliyo Fisher, novinarja, ki dela za rusko revijo Avtomir. Po uspe\u0161nem ribolovu s sinom je bil tako navdu\u0161en nad tem, da je napisal \u010dlanek o ribolovnem potovanju.","og_url":"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/","og_site_name":"Vodeni ribolov v slovenskem morju","article_publisher":"https:\/\/www.facebook.com\/seafishingslovenia\/","article_published_time":"2020-01-31T09:56:07+00:00","article_modified_time":"2020-01-31T09:56:08+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1.jpg","path":"\/home\/seafishing\/public_html\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1.jpg","size":"full","id":1664,"alt":"avtomir-ravija","pixels":786432,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Peter Kodre"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/en.seafishingslovenia.com\/#organization","name":"Ribolov v slovenskem morju","url":"https:\/\/en.seafishingslovenia.com\/","sameAs":["https:\/\/www.facebook.com\/seafishingslovenia\/","https:\/\/www.instagram.com\/seafishingslovenia\/","https:\/\/www.youtube.com\/channel\/UCX9hrnSWUMivTMsSQa_gQPw\/videos"],"logo":{"@type":"ImageObject","@id":"https:\/\/en.seafishingslovenia.com\/#logo","inLanguage":"sl-SI","url":"http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/2-layers.png","contentUrl":"http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/2-layers.png","width":91,"height":44,"caption":"Ribolov v slovenskem morju"},"image":{"@id":"https:\/\/en.seafishingslovenia.com\/#logo"}},{"@type":"WebSite","@id":"https:\/\/en.seafishingslovenia.com\/#website","url":"https:\/\/en.seafishingslovenia.com\/","name":"Ribolov v slovenskem morju vodeni morski ribolov","description":"","publisher":{"@id":"https:\/\/en.seafishingslovenia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/en.seafishingslovenia.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sl-SI"},{"@type":"ImageObject","@id":"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#primaryimage","inLanguage":"sl-SI","url":"http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1.jpg","contentUrl":"http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1.jpg","width":768,"height":1024,"caption":"avtomir-ravija"},{"@type":"WebPage","@id":"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#webpage","url":"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/","name":"Slovenske lampuge(delfinke) poznane tudi v Rusiji - Vodeni ribolov v slovenskem morju","isPartOf":{"@id":"https:\/\/en.seafishingslovenia.com\/#website"},"primaryImageOfPage":{"@id":"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#primaryimage"},"datePublished":"2020-01-31T09:56:07+00:00","dateModified":"2020-01-31T09:56:08+00:00","breadcrumb":{"@id":"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#breadcrumb"},"inLanguage":"sl-SI","potentialAction":[{"@type":"ReadAction","target":["http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/en.seafishingslovenia.com\/sl\/"},{"@type":"ListItem","position":2,"name":"Slovenske lampuge(delfinke) poznane tudi v Rusiji"}]},{"@type":"Article","@id":"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#article","isPartOf":{"@id":"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#webpage"},"author":{"@id":"https:\/\/en.seafishingslovenia.com\/#\/schema\/person\/25a30ee74697b01e244b0ffebbda054b"},"headline":"Slovenske lampuge(delfinke) poznane tudi v Rusiji","datePublished":"2020-01-31T09:56:07+00:00","dateModified":"2020-01-31T09:56:08+00:00","mainEntityOfPage":{"@id":"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#webpage"},"wordCount":61,"publisher":{"@id":"https:\/\/en.seafishingslovenia.com\/#organization"},"image":{"@id":"http:\/\/en.seafishingslovenia.com\/sl\/slovenske-lampugedelfinke-poznane-tudi-v-rusiji\/#primaryimage"},"thumbnailUrl":"http:\/\/en.seafishingslovenia.com\/wp-content\/uploads\/2020\/01\/48385214_264990397514053_964760323103916032_n-768x1024-1.jpg","articleSection":["Uncategorized @sl"],"inLanguage":"sl-SI"},{"@type":"Person","@id":"https:\/\/en.seafishingslovenia.com\/#\/schema\/person\/25a30ee74697b01e244b0ffebbda054b","name":"Peter Kodre","url":"http:\/\/en.seafishingslovenia.com\/sl\/author\/peterkodresampei\/"}]}},"_links":{"self":[{"href":"http:\/\/en.seafishingslovenia.com\/sl\/wp-json\/wp\/v2\/posts\/1660"}],"collection":[{"href":"http:\/\/en.seafishingslovenia.com\/sl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/en.seafishingslovenia.com\/sl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/en.seafishingslovenia.com\/sl\/wp-json\/wp\/v2\/users\/990004"}],"replies":[{"embeddable":true,"href":"http:\/\/en.seafishingslovenia.com\/sl\/wp-json\/wp\/v2\/comments?post=1660"}],"version-history":[{"count":1,"href":"http:\/\/en.seafishingslovenia.com\/sl\/wp-json\/wp\/v2\/posts\/1660\/revisions"}],"predecessor-version":[{"id":1665,"href":"http:\/\/en.seafishingslovenia.com\/sl\/wp-json\/wp\/v2\/posts\/1660\/revisions\/1665"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/en.seafishingslovenia.com\/sl\/wp-json\/wp\/v2\/media\/1664"}],"wp:attachment":[{"href":"http:\/\/en.seafishingslovenia.com\/sl\/wp-json\/wp\/v2\/media?parent=1660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/en.seafishingslovenia.com\/sl\/wp-json\/wp\/v2\/categories?post=1660"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/en.seafishingslovenia.com\/sl\/wp-json\/wp\/v2\/tags?post=1660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}